{"id":10492,"date":"2024-10-18T20:03:29","date_gmt":"2024-10-18T20:03:29","guid":{"rendered":"https:\/\/puelopatagonia.cl\/?post_type=noticias&#038;p=10492"},"modified":"2025-02-27T19:30:21","modified_gmt":"2025-02-27T19:30:21","slug":"buscan-voluntarios-que-quieran-pasar-21-dias-en-la-patagonia-apoyando-a-familias-en-sus-labores-de-campo","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/buscan-voluntarios-que-quieran-pasar-21-dias-en-la-patagonia-apoyando-a-familias-en-sus-labores-de-campo\/","title":{"rendered":"They are looking for volunteers who want to live 21 days in Puelo supporting families in their field work"},"content":{"rendered":"<p><em>En plena Cordillera de los Andes, en la comuna de Cocham\u00f3, familias de adultos mayores aprovechan la \u00e9poca de verano para preparar los insumos que los acompa\u00f1ar\u00e1n durante el crudo invierno. Con el fin de apoyar esa labor, la ONG Puelo Patagonia invita a j\u00f3venes de todo Chile a vivir la 4ta versi\u00f3n de este voluntariado que busca ser una experiencia de colaboraci\u00f3n entre las comunidades locales y los amantes de la naturaleza, y que pone en valor la riqueza cultural de la vida en el campo.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"596\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170842.png?resize=800%2C596&#038;ssl=1\" alt=\"\" class=\"wp-image-10494\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170842.png?w=946&amp;ssl=1 946w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170842.png?resize=300%2C224&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170842.png?resize=768%2C572&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170842.png?resize=16%2C12&amp;ssl=1 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Puelo Patagonia acaba de lanzar la convocatoria del Voluntariado Cordillera Puelo, una iniciativa que invita a voluntarios de todo Chile a trabajar codo a codo con familias de adultos mayores de los sectores cordilleranos de la comuna de Cocham\u00f3.<\/p>\n\n\n\n<p>En esta cuarta versi\u00f3n de este programa los participantes tendr\u00e1n la oportunidad de aprender y contribuir en labores dom\u00e9sticas y propias del campo, creando un impacto tangible en las vidas de quienes residen en estos alejados lugares de alto valor ambiental, donde las actividades de subsistencia se desarrollan en completa armon\u00eda con el entorno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"531\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170905.png?resize=800%2C531&#038;ssl=1\" alt=\"\" class=\"wp-image-10495\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170905.png?w=936&amp;ssl=1 936w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170905.png?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170905.png?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170905.png?resize=18%2C12&amp;ssl=1 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>\u201cDurante el verano los integrantes m\u00e1s j\u00f3venes de las familias trabajan en turismo y otras actividades o algunos han migrado del campo a la ciudad. Los adultos mayores tienen que hacer tareas que se les hacen cada vez m\u00e1s dif\u00edciles y desde esa necesidad surge este programa de voluntariado que ya se ha realizado en a\u00f1os anteriores y que para el \u00faltimo a\u00f1o tuvo m\u00e1s de 250 postulantes\u201d, explica Nicol\u00e1s Amadori, encargado del programa en Puelo Patagonia.<\/p>\n\n\n\n<p>En esa l\u00ednea, son m\u00e1s de 30 familias que han sido apoyadas gracias a estas experiencias. Y uno de los aspectos que m\u00e1s han destacado tanto los voluntarios como la comunidad son las relaciones duraderas que deja este programa.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170926.png?resize=800%2C530&#038;ssl=1\" alt=\"\" class=\"wp-image-10496\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170926.png?w=938&amp;ssl=1 938w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170926.png?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170926.png?resize=768%2C509&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/Captura-de-pantalla-2025-02-19-170926.png?resize=18%2C12&amp;ssl=1 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Esto gracias a que a cada voluntario se le asigna una familia anfitriona con la que comparte experiencias y trabaja para preparar durante 21 d\u00edas los insumos que acompa\u00f1ar\u00e1n a los adultos mayores durante el crudo invierno cordillerano. \u201cEsto permite una inmersi\u00f3n profunda y genuina en la cultura local y las tradiciones, generando conexiones duraderas y un intercambio valioso de conocimientos y experiencias\u201d, se\u00f1ala Amadori.<\/p>\n\n\n\n<p>Los voluntarios realizan actividades propias del campo y estas var\u00edan seg\u00fan las necesidades de cada familia, como trabajo en la huerta, recolecci\u00f3n de le\u00f1a, reparaciones menores, acompa\u00f1amiento a familias, apoyo en actividades dom\u00e9sticas, arreo de animales, etc.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"535\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?resize=800%2C535&#038;ssl=1\" alt=\"\" class=\"wp-image-5610\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?resize=300%2C201&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?resize=1024%2C685&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?resize=1536%2C1027&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?resize=2048%2C1369&amp;ssl=1 2048w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/10\/2.-Puelo-Patagonia-que-es-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>En una entrevista sobre el voluntariado que se realiz\u00f3 el a\u00f1o pasado, Domingo Urrutia, poblador de Puerto Urrutia y parte de una de las familias beneficiadas por este voluntariado, destac\u00f3 que los participantes \u201csiempre se van de aqu\u00ed con una experiencia de ac\u00e1. Los voluntarios se van contentos porque uno les ense\u00f1a lo que sabe y lo que ellos ignoran hasta ese momento. Y eso lo valoramos tanto nosotros como ellos\u201d.<\/p>\n\n\n\n<p>Para esta cuarta versi\u00f3n se podr\u00e1 postular desde el 20 de octubre hasta el 03 de noviembre del 2024. Luego de ser seleccionados, comenzar\u00e1n su voluntariado el 14 de enero del 2025 que finalizar\u00e1 el 4 de febrero del mismo a\u00f1o.<\/p>\n\n\n\n<p>Actualizaci\u00f3n: actualmente las postulaciones se encuentran cerradas. Te invitamos a conocer m\u00e1s de este proyecto en nuestra web y a postular en octubre de 2025. <\/p>\n\n\n\n<p><\/p>","protected":false},"featured_media":10234,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[31],"class_list":["post-10492","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categorias_noticias-fortalecimiento-social"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/10492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":3,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/10492\/revisions"}],"predecessor-version":[{"id":10499,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/10492\/revisions\/10499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/10234"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=10492"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=10492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}