{"id":11263,"date":"2025-10-21T23:36:55","date_gmt":"2025-10-21T23:36:55","guid":{"rendered":"https:\/\/puelopatagonia.cl\/?post_type=noticias&#038;p=11263"},"modified":"2025-10-22T14:28:56","modified_gmt":"2025-10-22T14:28:56","slug":"conserva-pucheguin-logra-superar-el-80-de-la-meta-el-llamado-es-a-los-chilenos-a-sumarse-a-esta-causa","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/conserva-pucheguin-logra-superar-el-80-de-la-meta-el-llamado-es-a-los-chilenos-a-sumarse-a-esta-causa\/","title":{"rendered":"Conserva Pucheg\u00fc\u00edn logra superar el 80% de la meta: \u201cEl llamado es a los chilenos a sumarse a esta causa\u201d"},"content":{"rendered":"<p class=\"\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><em>Luego de que en 2022 el Fundo Pucheg\u00fc\u00edn en Cocham\u00f3 fuera puesto en venta, cinco organizaciones nacionales e internacionales lanzaron una campa\u00f1a para recaudar USD 78MM para comprar y proteger este lugar que alberga grandes monta\u00f1as, bosques de alerces milenarios y especies en peligro de extinci\u00f3n como el huemul.&nbsp;<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><em>En su recta final, hacen un llamado directo a los chilenos para poder completar el 20% restante de uno de los proyectos de recaudaci\u00f3n para la conservaci\u00f3n m\u00e1s grandes que se ha realizado en nuestro pa\u00eds.<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><em>Una vez que se compre la tierra, se buscar\u00e1 crear un \u00e1rea protegida mixta que asegure la conservaci\u00f3n del ecosistema y resguarde los usos hist\u00f3ricos y actuales del lugar.<\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?resize=800%2C534&#038;ssl=1\" alt=\"\" class=\"wp-image-11265\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?resize=1536%2C1025&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-2.jpg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\">Con el 80% de la meta recaudada, el proyecto Conserva Pucheg\u00fc\u00edn se ha posicionado como una de las iniciativas de conservaci\u00f3n m\u00e1s llamativas en Chile, luego de que un grupo compuesto por organizaciones nacionales e internacionales se propusieran reunir un millonario monto para conservar 133 mil hect\u00e1reas en la comuna de Cocham\u00f3, Regi\u00f3n de Los Lagos.<\/p>\n\n\n\n<p class=\"\">La idea de iniciar una campa\u00f1a para lograr comprar el lugar, nace luego de la puesta en venta del Fundo Pucheg\u00fc\u00edn el a\u00f1o 2022. La publicaci\u00f3n de esta gran extensi\u00f3n de tierra levant\u00f3 las alarmas, y a principios del a\u00f1o 2024 Puelo Patagonia lider\u00f3 y logr\u00f3 conformar una alianza con The Nature Conservancy, Freyja Foundation, Patagonia Inc. y Wyss Foundation, que comenz\u00f3 a movilizar fondos en Chile y en el mundo para poder comprarlo y protegerlo, trabajo que se realiz\u00f3 en paralelo al levantamiento de informaci\u00f3n en terreno para determinar los usos y la importancia a nivel local de este lugar que representa un tercio de la comuna.<\/p>\n\n\n\n<p class=\"\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?fit=800%2C534&amp;ssl=1\" alt=\"\" class=\"wp-image-11266\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?resize=1536%2C1025&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/PP-CAMARA-TRAMPA-COCHAMO-2023-1.jpg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\">Se calcula, por ejemplo, que 1400 familias de Cocham\u00f3 dependen del agua dulce que guarda este lugar en su extensa red hidrogr\u00e1fica, que incluye 507 hect\u00e1reas de glaciares, 41 kil\u00f3metros de ribera de lagos y lagunas, adem\u00e1s de los 372 kil\u00f3metros de ribera de r\u00edos, y 150 hect\u00e1reas de humedales y turberas.&nbsp;<\/p>\n\n\n\n<p class=\"\">El Fundo Pucheg\u00fc\u00edn es considerado adem\u00e1s uno de los pocos refugios clim\u00e1ticos que quedan en el mundo. Su superficie incluye 58 mil hect\u00e1reas de bosque primario y se estima que alberga casi el 11% de los alerces del mundo, especie que es capaz de almacenar m\u00e1s carbono incluso que \u00e1rboles del Amazonas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1686\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?fit=800%2C527&amp;ssl=1\" alt=\"\" class=\"wp-image-11267\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?resize=1024%2C675&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?resize=768%2C506&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?resize=1536%2C1012&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?resize=2048%2C1349&amp;ssl=1 2048w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Marcelo-Salazar-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\">Adem\u00e1s sus famosas paredes de granito y pr\u00edstinos r\u00edos son reconocidos mundialmente como importantes atractivos tur\u00edsticos que aportan a la econom\u00eda local de toda una regi\u00f3n.<\/p>\n\n\n\n<p class=\"\">Es por ello que los ojos de la comunidad local, amantes de la naturaleza, conservacionistas y deportistas est\u00e1n puestos en lograr la meta que permitir\u00e1 proteger este territorio de alto valor ecol\u00f3gico y cultural.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?fit=800%2C600&amp;ssl=1\" alt=\"\" class=\"wp-image-11268\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-3-scaled.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\"><strong>Un territorio nacional protegido por los chilenos<\/strong><\/p>\n\n\n\n<p class=\"\">\u201cEsta es una iniciativa que nace en Chile y se impulsa a nivel nacional e internacional. Lo que buscamos es que este lugar sea de todos los chilenos protegido bajo la ley chilena\u201d, se\u00f1al\u00f3 Andr\u00e9s Diez, director ejecutivo de la Puelo Patagonia, ONG que trabaja hace 12 a\u00f1os por la conservaci\u00f3n de la comuna de Cocham\u00f3 y que est\u00e1 liderando la iniciativa Conserva Pucheg\u00fc\u00edn.&nbsp;<\/p>\n\n\n\n<p class=\"\">La estrategia que han ocupado para recaudar el 80% de los fondos en un a\u00f1o y medio ha sido principalmente a trav\u00e9s de donaciones de fil\u00e1ntropos, organizaciones en Chile y el extranjero, y tambi\u00e9n parte de lo recaudado ha sido gracias al aporte distintas personas provenientes de 17 pa\u00edses, siendo Chile uno de pa\u00edses con m\u00e1s cantidad de personas que han donado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"644\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226-1024x824.jpg?resize=800%2C644&#038;ssl=1\" alt=\"\" class=\"wp-image-11269\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226.jpg?resize=1024%2C824&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226.jpg?resize=300%2C241&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226.jpg?resize=768%2C618&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226.jpg?resize=1536%2C1236&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226.jpg?resize=15%2C12&amp;ssl=1 15w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226.jpg?w=1707&amp;ssl=1 1707w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos_-Valentina-Thenoux-2-1-scaled-e1761089582226.jpg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\">\u201cSi bien la filantrop\u00eda ambiental es algo que todav\u00eda no ha ganado suficiente espacio entre los chilenos, nuestro foco ahora es que ese \u00faltimo 20% de los fondos sea con sentimiento nacional, que nos involucremos todos en proteger lugares como estos. El llamado es a los chilenos a unirnos por esta causa para que entre todos logremos que se mantenga para esta y futuras generaciones\u201d, destac\u00f3 Diez.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1810\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?fit=800%2C566&amp;ssl=1\" alt=\"\" class=\"wp-image-11275\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?resize=1024%2C724&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?resize=1536%2C1086&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?resize=2048%2C1448&amp;ssl=1 2048w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia-2-1-scaled.png?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\"><strong>Un modelo \u00fanico: conservaci\u00f3n y desarrollo local<\/strong><\/p>\n\n\n\n<p class=\"\">Luego de recaudar el monto total, el predio ser\u00e1 adquirido por la Fundaci\u00f3n Conserva Pucheg\u00fc\u00edn, organizaci\u00f3n chilena sin fines de lucro, que fue creada con el objetivo de resguardar a perpetuidad el lugar.<\/p>\n\n\n\n<p class=\"\">Lo innovador de esta iniciativa de conservaci\u00f3n es que dentro de su estrategia propone un modelo h\u00edbrido de protecci\u00f3n, destinando alrededor de&nbsp;20.000 hect\u00e1reas para el uso y desarrollo, siempre y cuando esto no perjudique los objetivos de conservaci\u00f3n, buscando as\u00ed proteger la naturaleza y al mismo tiempo reconocer los v\u00ednculos hist\u00f3ricos de la comunidad con este lugar.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?fit=800%2C600&amp;ssl=1\" alt=\"\" class=\"wp-image-11272\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Puelo-Patagonia.jpeg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\">\u201cLos vecinos, sobre todo los pobladores que viven en la cordillera, usan el Fundo Pucheg\u00fc\u00edn para llevar a sus animales, sacar le\u00f1a o abastecerse de agua. Por eso estamos trabajando en conjunto desde el inicio de esta iniciativa, para que esos estilos de vida se mantengan, porque es gracias a ellos y sus modos de vida que estos lugares se han mantenido as\u00ed de pr\u00edstinos\u201d, dijo Tatiana Sandoval, encargada de Vinculaci\u00f3n Comunitaria de Puelo Patagonia.<\/p>\n\n\n\n<p class=\"\">Por otro lado, las m\u00e1s de&nbsp;110.000 hect\u00e1reas que existen en las zonas altas del terreno y que permanecen casi sin intervenci\u00f3n, estar\u00e1n bajo una categor\u00eda de conservaci\u00f3n estricta de Parque, con el fin de proteger los lugares inexplorados que albergan bosques de alerce y son h\u00e1bitat de especies en serio peligro como el huemul.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1334\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?fit=800%2C534&amp;ssl=1\" alt=\"\" class=\"wp-image-11273\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?resize=1536%2C1025&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2025\/10\/Creditos-Daniel-Pastene-3.jpg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"\">Una vez inscrita la tierra, se proteger\u00e1 legalmente bajo un Derecho Real de Conservaci\u00f3n como primer paso y luego se avanzar\u00e1 hacia la aplicaci\u00f3n de dos categor\u00edas de protecci\u00f3n oficial, siempre con miras a cumplir el objetivo final: donar un \u00e1rea protegida \u00edntegra al Estado de Chile.<\/p>\n\n\n\n<p class=\"\">Juan Jos\u00e9 Donoso, director de The Nature Conservancy Chile, agreg\u00f3 que \u201cla conservaci\u00f3n efectiva de Pucheg\u00fc\u00edn solo es posible cuando se construye en conjunto. Este proceso ha demostrado el valor de colaborar con comunidades locales, organizaciones y actores diversos para planificar la conservaci\u00f3n del territorio, reconociendo que proteger la naturaleza implica tambi\u00e9n cuidar los v\u00ednculos humanos que la han sostenido a lo largo del tiempo.\u201d<\/p>","protected":false},"featured_media":11277,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[30],"class_list":["post-11263","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categorias_noticias-conservacion"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/11263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":5,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/11263\/revisions"}],"predecessor-version":[{"id":11280,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/11263\/revisions\/11280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/11277"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=11263"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=11263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}