{"id":2396,"date":"2021-04-30T20:40:00","date_gmt":"2021-04-30T20:40:00","guid":{"rendered":"https:\/\/zyn.xar.mybluehost.me\/website_cbdee90b\/noticias\/grupo-patagonia-mar-y-tierra-declaracion-sobre-la-lenta-reaccion-tras-el-desastre-ambiental-en-el-fiordo-comau\/"},"modified":"2022-07-07T21:39:35","modified_gmt":"2022-07-07T21:39:35","slug":"grupo-patagonia-mar-y-tierra-declaracion-sobre-la-lenta-reaccion-tras-el-desastre-ambiental-en-el-fiordo-comau","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/grupo-patagonia-mar-y-tierra-declaracion-sobre-la-lenta-reaccion-tras-el-desastre-ambiental-en-el-fiordo-comau\/","title":{"rendered":"Grupo Patagonia, Mar y Tierra: Declaraci\u00f3n sobre la lenta reacci\u00f3n tras el desastre ambiental en el fiordo Comau"},"content":{"rendered":"<p>Frente al desastre ambiental que ha afectado recientemente al Fiordo Comau, en la Regi\u00f3n de Los Lagos, y al lento avance de acciones o medidas para mitigar y prevenir otros eventos de este tipo, como Grupo de Trabajo Patagonia Mar y Tierra compartimos la siguiente declaraci\u00f3n, dirigida principalmente a tomadores de decisi\u00f3n (gobierno, servicios p\u00fablicos, legisladores), y a la industria:<\/p>\n<p>&#8211;&nbsp; &nbsp; La mortalidad de salmones y la consecuente contaminaci\u00f3n del Fiordo Comau debido a una floraci\u00f3n de algas nocivas (FAN) en este rico y diverso ecosistema, es una situaci\u00f3n tremendamente grave que exige adoptar medidas urgentes para prevenir y mitigar que estas situaciones afecten otros sitios fr\u00e1giles y de alta relevancia ecosist\u00e9mica, social o cultural.<\/p>\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;El Fiordo Comau es un sitio de biodiversidad sin igual, donde es posible encontrar importantes y \u00fanicos bancos de corales de aguas fr\u00edas de baja profundidad, colonias de mam\u00edferos marinos y aves, y un importante n\u00famero de especies de cet\u00e1ceos, algunos en peligro de conservaci\u00f3n. Debido a su fragilidad, presenta un alto riesgo ante impactos clim\u00e1ticos, que se pueden ver incrementados por el ingreso de nutrientes adicionales al ecosistema producto de la salmonicultura, que presenta una alta concentraci\u00f3n en el lugar. Esta condici\u00f3n de alerta o fragilidad ya hab\u00eda sido advertida por la ciencia en \u00e1reas relevantes en t\u00e9rminos de salud ecosist\u00e9mica<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>, adem\u00e1s de haber relevado la necesidad de comprender el impacto acu\u00edcola m\u00e1s all\u00e1 de los centros de engorda<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>.<\/p>\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Frente a estos eventos graves es urgente la incorporaci\u00f3n del enfoque ecosist\u00e9mico en la actividad acu\u00edcola, incluyendo indicadores que permitan decisiones fundadas en evidencia cient\u00edfica para evitar la expansi\u00f3n o incluso cerrar la operaci\u00f3n de la salmonicultura en sitios fr\u00e1giles y \u00fanicos como el Fiordo Comau. Es importante avanzar en una zonificaci\u00f3n que excluya la salmonicultura de \u00c1reas Marinas Protegidas para disminuir el impacto antr\u00f3pico, ya que son \u00e1reas fr\u00e1giles reconocidas por su biodiversidad e importancia sociocultural.<\/p>\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Otro aspecto prioritario que se debe evaluar y regular de manera estricta es el manejo oportuno y transparente de mortalidades, dado que es inaceptable que estos eventos sean fuente de una alta contaminaci\u00f3n debido a la descomposici\u00f3n. Esto, junto con plantear la existencia de una investigaci\u00f3n exhaustiva y una revisi\u00f3n de protocolos de gesti\u00f3n de residuos en la industria. A su vez, se deben reforzar monitoreos m\u00e1s estrictos y efectivos.<\/p>\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; En t\u00e9rminos m\u00e1s amplios, el Estado debe reconocer y subsanar la necesidad de mayor proactividad frente a este tipo de riesgos, lo que requiere necesariamente cambios sustantivos en materia ambiental y sanitaria del marco normativo de la industria acu\u00edcola para evitar repetir estas situaciones.<\/p>\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Las organizaciones que conforman el Grupo de Trabajo Patagonia Mar y Tierra coinciden en el llamado realizado por investigadores a establecer un monitoreo ambiental permanente, con m\u00e1s y mejor investigaci\u00f3n cient\u00edfica y disponibilidad de datos para la toma de decisiones, as\u00ed como a establecer protocolos efectivos para la oportuna gesti\u00f3n de residuos en caso de ocurrencia de mortalidad masiva. Adem\u00e1s, reiteran la urgente necesidad de evaluar de manera sistem\u00e1tica y con informaci\u00f3n basada en evidencia cient\u00edfica la exclusi\u00f3n de la salmonicultura en sitios cr\u00edticos para la biodiversidad, comunidades costeras y pueblos originarios, incluyendo \u00c1reas Protegidas, y revisar la distribuci\u00f3n espacial de la salmonicultura con un enfoque actualizado de ordenamiento territorial y basado en el cambio clim\u00e1tico.<\/p>\n<p>*Patagonia Mar y Tierra es un grupo de organizaciones de la sociedad civil que busca mejorar la conservaci\u00f3n de la Patagonia chilena, y es integrado por Aumen, Centro Ballena Azul, Fundaci\u00f3n Melimoyu, Fundaci\u00f3n Omora, Fundaci\u00f3n Terram, Puelo Patagonia, Round River, The Pew Charitable Trusts y WWF Chile, apoyados t\u00e9cnicamente por el Programa Austral Patagonia de la UACh.<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <a href=\"https:\/\/arclim.mma.gob.cl\/\" target=\"_blank\" rel=\"noopener\">https:\/\/arclim.mma.gob.cl\/<\/a><\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <a href=\"https:\/\/www.incar.cl\/wp-content\/uploads\/2021\/01\/Revista.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.incar.cl\/wp-content\/uploads\/2021\/01\/Revista.pdf<\/a><\/p>\n","protected":false},"featured_media":2446,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[],"class_list":["post-2396","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":1,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2396\/revisions"}],"predecessor-version":[{"id":2447,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2396\/revisions\/2447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/2446"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=2396"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=2396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}