{"id":2399,"date":"2021-07-20T20:40:00","date_gmt":"2021-07-20T20:40:00","guid":{"rendered":"https:\/\/zyn.xar.mybluehost.me\/website_cbdee90b\/noticias\/comunidades-piden-que-el-rio-puelo-sea-declarado-reserva-de-agua\/"},"modified":"2022-07-07T21:31:12","modified_gmt":"2022-07-07T21:31:12","slug":"comunidades-piden-que-el-rio-puelo-sea-declarado-reserva-de-agua","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/comunidades-piden-que-el-rio-puelo-sea-declarado-reserva-de-agua\/","title":{"rendered":"Comunidades piden que el r\u00edo Puelo sea declarado Reserva de Agua"},"content":{"rendered":"<p><em>La campa\u00f1a #pueloreservadeagua invita a la ciudadan\u00eda a firmar en apoyo a la solicitud que busca proteger parte del&nbsp; caudal del r\u00edo Puelo, contribuyendo as\u00ed a la conservaci\u00f3n de la naturaleza y el desarrollo local.<\/em><\/p>\n\n\n\n<p>Con un masivo llamado a apoyar la solicitud para declarar al r\u00edo Puelo como caudal de reserva, la comunidad de Puelo y Cocham\u00f3 lanz\u00f3 la campa\u00f1a #PueloReservadeAgua. Esta iniciativa busca sumar 40 mil firmas a trav\u00e9s del sitio web <a href=\"http:\/\/www.pueloreservadeagua.cl\" target=\"_blank\" rel=\"noopener\">www.pueloreservadeagua.cl<\/a>, para enviar una carta al Presidente Sebasti\u00e1n Pi\u00f1era, pidi\u00e9ndole que d\u00e9 urgencia a la solicitud de los vecinos de reservar el r\u00edo Puelo para la conservaci\u00f3n de la naturaleza y el desarrollo local.&nbsp;<\/p>\n\n\n\n<p>Proteger el r\u00edo Puelo es urgente frente a la crisis clim\u00e1tica global y el creciente escenario de sequ\u00edas que ha comenzado a afectar a los habitantes y la biodiversidad de la zona. Este a\u00f1o se decretaron 3 provincias en escasez h\u00eddrica en la Regi\u00f3n de Los Lagos:&nbsp; Osorno, Chilo\u00e9 y Llanquihue. Dentro de esta \u00faltima se encuentra localizado el r\u00edo Puelo en la comuna de Cocham\u00f3.<\/p>\n\n\n\n<p>Otra de las amenazas que enfrenta la cuenca del r\u00edo Puelo es la privatizaci\u00f3n: gran parte de su caudal est\u00e1 en manos de privados lo que posibilita la comercializaci\u00f3n de sus aguas. En ese sentido se otorgan grandes derechos de aprovechamiento seg\u00fan disponibilidad y sin distinguir la vocaci\u00f3n productiva del territorio o del inter\u00e9s de sus habitantes. Permitiendo el otorgamiento, pr\u00e1cticamente a perpetuidad, de caudales con fines especulativos a empresas o privados con nula relaci\u00f3n con el territorio.<\/p>\n\n\n\n<p>Lamentablemente s\u00f3lo 12 de los 1.251 r\u00edos del pa\u00eds cuentan con un caudal de reserva para la conservaci\u00f3n. Es decir, apenas el 1% de los r\u00edos en Chile se encuentra, de alguna manera &#8220;protegido&#8221; a trav\u00e9s de las llamadas Reserva de Caudales. Promover esta declaratoria para el r\u00edo Puelo funciona como una primera medida para lograr que a futuro se desarrolle una ley que conserve de forma integral los ecosistemas de la cuenca y sus comunidades aleda\u00f1as.<\/p>\n\n\n\n<p><strong>What is a water reserve?&nbsp;<\/strong><\/p>\n\n\n\n<p>The Chilean water code establishes in its article 147 bis that the President of the Republic can declare, by presidential decree, a water reserve. This can occur when there is a need to supply the local population or also due to exceptional circumstances of the place and it is considered to be of national interest.<\/p>\n\n\n\n<p>La reserva de agua reconoce el valor ecol\u00f3gico y social de determinados caudales y limita de forma significativa el otorgamiento de derechos de aprovechamiento de aguas, protegi\u00e9ndolo frente a las industrias que quieran aprovecharse de sus condiciones especiales, como, por ejemplo, la miner\u00eda e hidroel\u00e9ctricas.<\/p>\n\n\n\n<p>El 2019 la comunidad de Puelo y Cocham\u00f3 enviaron una carta al Presidente de la Rep\u00fablica solicitando la Reserva de Agua en el R\u00edo Puelo, petitorio que a\u00fan no ha sido respondido. Hoy necesitamos 40 mil firmas para apoyar a la comunidad y que el r\u00edo sea declarado como Reserva de Agua. S\u00famate en <a href=\"http:\/\/www.pueloreservadeagua.cl\" target=\"_blank\" rel=\"noopener\">www.pueloreservadeagua.cl<\/a> y juntos cambiemos el curso del r\u00edo Puelo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" height=\"800\" width=\"800\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/puelo\/wp-content\/uploads\/2021\/07\/Gra%CC%81fica-1-RRSS-Lanzamiento-1024x1024.jpg?resize=800%2C800&#038;ssl=1\" alt=\"\" class=\"wp-image-3967\"\/><\/figure>","protected":false},"featured_media":254,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[],"class_list":["post-2399","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":1,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2399\/revisions"}],"predecessor-version":[{"id":2437,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2399\/revisions\/2437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/254"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=2399"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=2399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}