{"id":2400,"date":"2021-08-30T20:40:00","date_gmt":"2021-08-30T20:40:00","guid":{"rendered":"https:\/\/zyn.xar.mybluehost.me\/website_cbdee90b\/noticias\/el-rio-puelo-y-su-rol-fundamental-para-enfrentar-el-cambio-climatico-en-chile\/"},"modified":"2022-07-07T21:35:08","modified_gmt":"2022-07-07T21:35:08","slug":"el-rio-puelo-y-su-rol-fundamental-para-enfrentar-el-cambio-climatico-en-chile","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/el-rio-puelo-y-su-rol-fundamental-para-enfrentar-el-cambio-climatico-en-chile\/","title":{"rendered":"El r\u00edo Puelo y su rol fundamental para enfrentar el cambio clim\u00e1tico en Chile"},"content":{"rendered":"<p><em>El r\u00edo Puelo es uno de los pocos r\u00edos del mundo que fluye libre de cordillera a mar. Sus aguas y ecosistemas se encuentran en un excelente estado de conservaci\u00f3n lo cual es esencial tanto para las personas y ecosistemas como para estudiar los escenarios futuros que traen consigo el calentamiento global.<\/em><\/p>\n\n\n\n<p>El r\u00edo Puelo, ubicado en la Patagonia norte, tiene tres caracter\u00edsticas que lo hacen esencial para enfrentar el cambio clim\u00e1tico y que fueron descritas en el \u00faltimo informe del Grupo Intergubernamental de Expertos sobre el Cambio Clim\u00e1tico (IPCC). Donde seg\u00fan un atlas inserto dentro de este mismo, se muestra que Chile ser\u00eda uno de los pa\u00edses m\u00e1s impactados por el calentamiento global con una fuerte disminuci\u00f3n de sus precipitaciones.<\/p>\n\n\n\n<p>En primer lugar, el r\u00edo Puelo es uno de los pocos r\u00edos de las zonas densamente pobladas de Chile que a\u00fan presenta altos niveles de calidad de agua. Esto quiere decir que su caudal no tiene intervenciones significativas y sus ecosistemas aleda\u00f1os presentan un excelente estado conservaci\u00f3n.<\/p>\n\n\n\n<p>\u201cLa cuenca del r\u00edo Puelo con su bosque nativo es una gran esponja que capta el agua y que la entrega de forma adecuada en verano y oto\u00f1o. En escenarios futuros, donde el agua va escasear, necesitamos que esta esponja se siga manteniendo en excelente estado de conservaci\u00f3n\u201d, asegura Jorge Le\u00f3n, Doctor en Ciencias Forestales e ingeniero en Acuicultura de la Universidad Austral de Chile.<\/p>\n\n\n\n<p>En segundo lugar, el r\u00edo Puelo ha sido monitoreado por 70 a\u00f1os, logrando informaci\u00f3n cient\u00edfica que demuestra el impacto del cambio clim\u00e1tico en el r\u00edo. Condici\u00f3n que no ser\u00eda posible si el r\u00edo se encontrara intervenido por hidroel\u00e9ctricas o desviaciones de agua importantes, ya que no se le podr\u00eda atribuir sus cambios directamente al cambio clim\u00e1tico.<\/p>\n\n\n\n<p>Y tercer punto muy relevante, es que los aportes de agua dulce del r\u00edo Puelo son fundamentales para la salud de los ecosistemas marinos situados en su desembocadura (Fiordo y Seno de Reloncav\u00ed). Ya que estos albergan especies \u00fanicas adaptadas a aguas dulces y saladas y que dependen de los nutrientes que arrastra el r\u00edo en su flujo de cordillera a mar. Alteraciones de este balance podr\u00edan degradar gravemente el ecosistema y elevar los niveles de contaminaci\u00f3n.<\/p>\n\n\n\n<p>\u201cConservar el r\u00edo Puelo va a tener directa relaci\u00f3n con asegurar el agua a las comunidades locales, pero adem\u00e1s permite conservar servicios y funciones ecosist\u00e9micas tanto en el r\u00edo como en el fiordo y los sistemas costeros aleda\u00f1os\u201d, se\u00f1ala Jorge Le\u00f3n.<\/p>\n\n\n\n<p>Proteger el r\u00edo Puelo, adem\u00e1s de asegurar un beneficio a la comunidad local y a las zonas de estuarios y bah\u00edas, permite conservar un gran sensor para anticipar lo que podr\u00eda ocurrir en los r\u00edos de la Patagonia norte.&nbsp;<\/p>\n\n\n\n<p>\u201cEl que sea reserva el r\u00edo Puelo no quiere decir que se estanque el desarrollo en un territorio quiere decir que se consolida, quiere decir que le permite hacer inversiones a mediano y a largo plazo a intereses que est\u00e1n preocupados por cuidar el medio ambiente\u201d, coment\u00f3 V\u00edctor Vaccaro Dirigente Social y Empresario Tur\u00edstico.<\/p>\n\n\n\n<p><strong>\u00daltimas investigaciones de Puelo<\/strong><\/p>\n\n\n\n<p>En julio de 2021, un grupo de investigadores public\u00f3 un estudio en la Revista Frontiers of Marine Science sobre los efectos que tienen las tendencias clim\u00e1ticas y los cambios en la cubierta de suelo en el r\u00edo Puelo y su desembocadura en el Estuario del Reloncav\u00ed. Los resultados indicaron claras propensiones hacia sequ\u00edas m\u00e1s largas e intensas en el r\u00edo Puelo, que podr\u00edan aumentar las condiciones locales de eutrofizaci\u00f3n (acumulaci\u00f3n de residuos org\u00e1nicos que causa la proliferaci\u00f3n de ciertas algas) en el Estuario de Reloncav\u00ed.<\/p>\n\n\n\n<p>El r\u00edo Puelo mostr\u00f3 una importante reducci\u00f3n de su caudal en verano y oto\u00f1o, mostrando menos inundaciones prolongadas y&nbsp; menor influencia del agua dulce en el estuario producto de una marcada disminuci\u00f3n de las precipitaciones.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/lh4.googleusercontent.com\/0-vIpbo5Axaacx5akRmDnEk8eaW6g0tC0kZ5s6QZ8OUareeQn7yN6mZWLGWmul13NgXtbTYCg2NTlpsYn03JLMnXepizdf88iCn5SwummLaKZlYDO_hJpN6I8h1PhzayNO6czOYQ=s0\" alt=\"\"\/><\/figure>\n\n\n\n<p>Gr\u00e1fica sobre el caudal de verano del r\u00edo Puelo entre 1950 y 2070. Realizada por los investigadores Dr. Rodrigo Aguayo (UdeC) y Dr. Jorge Le\u00f3n Mu\u00f1oz (UCSC \u2013 INCAR)<\/p>\n\n\n\n<p><strong>Campa\u00f1a #PueloReservadeAgua<\/strong><\/p>\n\n\n\n<p>El a\u00f1o 2019, 39 organizaciones locales enviaron una carta al presidente Sebasti\u00e1n Pi\u00f1era pidiendo la declaraci\u00f3n del r\u00edo como una Reserva de Agua, solicitud que no tuvo respuesta, por lo que las comunidades de Puelo y Cocham\u00f3 lanzaron la campa\u00f1a #PueloReservadeAgua para presionar al gobierno a responder este petitorio con urgencia.<\/p>\n\n\n\n<p>Una reserva de agua (la \u00fanica figura de protecci\u00f3n de r\u00edos) reconoce el valor ecol\u00f3gico y social de determinados caudales y limita de forma significativa el otorgamiento de derechos de aprovechamiento de aguas, protegi\u00e9ndolo frente a las industrias que quieran aprovecharse de sus condiciones especiales, como, por ejemplo, la miner\u00eda e hidroel\u00e9ctricas.<\/p>\n\n\n\n<p>\u201cLa urgencia de concretar la campa\u00f1a #PueloReservadeAgua, es alt\u00edsima principalmente si consideramos las proyecciones de cambio clim\u00e1tico entregadas por el&nbsp; IPCC, que indican que la zona de Chile donde se encuentra la cuenca del r\u00edo Puelo va a ser la m\u00e1s impactada a nivel mundial. Los r\u00edos van a resentir estas proyecciones, la cuenca tambi\u00e9n lo va a resentir\u201d, indica Jorge Le\u00f3n.<\/p>\n\n\n\n<p>\u201cLas principales consecuencias tienen que ver con la escasez del recurso h\u00eddrico y el aumento en las temperaturas. Es urgente entonces asegurar la protecci\u00f3n del caudal del r\u00edo Puelo para el uso humano y la conservaci\u00f3n de los ecosistemas naturales de esta cuenca frente a otros usos como los proyectos hidroel\u00e9ctricos, los cuales disminuyen todav\u00eda m\u00e1s la disponibilidad de agua\u201d, se\u00f1al\u00f3 Gabriel G\u00f3mez, ge\u00f3grafo de la Corporaci\u00f3n Puelo Patagonia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/lh5.googleusercontent.com\/E_PAlWcmnMRsJNrb89itivN3NYxK8GS8K9g5NrTL1inO30FFkjs32omfThDp399gPT7tIdR2Uq20jgm5gZOA6831Dc3BrTfVRTsNVR65wbdpifooF27F-b3uo-PO38WdTTrI6A86=s0\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/lh5.googleusercontent.com\/NIhPtu-BCt4Il9hCfzCfb5X_PfebwzgOgdpZR7hOGFsaCGzvPUFZYdw7uCyvcZzjJMp4oDpij_WcZpVj8az3hLhbrdELy6xqVWq3Ivik2ISDU-di7htcqjwIHt7CTy8j_5has-Co=s0\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n\n\n\n<p><\/p>","protected":false},"featured_media":2440,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[],"class_list":["post-2400","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":1,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2400\/revisions"}],"predecessor-version":[{"id":2441,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/2400\/revisions\/2441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/2440"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=2400"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=2400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}