{"id":3717,"date":"2022-11-10T12:30:51","date_gmt":"2022-11-10T12:30:51","guid":{"rendered":"https:\/\/zyn.xar.mybluehost.me\/website_cbdee90b\/?post_type=noticias&#038;p=3717"},"modified":"2022-11-10T12:32:26","modified_gmt":"2022-11-10T12:32:26","slug":"comunidad-de-cochamo-espera-pronunciamiento-de-bienes-nacionales-para-la-creacion-de-un-santuario-de-la-naturaleza","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/comunidad-de-cochamo-espera-pronunciamiento-de-bienes-nacionales-para-la-creacion-de-un-santuario-de-la-naturaleza\/","title":{"rendered":"Comunidad de Cocham\u00f3 espera pronunciamiento de Bienes Nacionales para la creaci\u00f3n de un Santuario de la Naturaleza"},"content":{"rendered":"<p><em><em>El valle de Cocham\u00f3 no est\u00e1 protegido y es por esto que hace m\u00e1s de una d\u00e9cada la comunidad local protege el lugar del turismo masivo y otras amenazas como el desarrollo inmobiliario y la instalaci\u00f3n de hidroel\u00e9ctricas. Hoy la comunidad est\u00e1 a la espera del pronunciamiento de las autoridades para que se declare un Santuario de la Naturaleza en el Valle Cocham\u00f3.<\/em> <\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/lh6.googleusercontent.com\/Yn0sXj9UWe_sj8LvNhNKhbu2reSNIAARzhK42huFiDDX2Xa2cM9jbh8sdLzj7tl_NMLvW315mu651KdInDyVCIsAcsS3wTj8wajFKBZFo4J2eEtGh2GK2Z3EcLeVz6thCJuyOGN0F_HgmXeEUW6y3Ul8lElPTRIMlP6yYvOrUmLACY945DQDdezc7jPruQ\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Vista al Anfiteatro por Daniel Pastene<\/figcaption><\/figure>\n\n\n\n<p>El Valle Cocham\u00f3 es reconocido nacional e internacionalmente por su cultura \u00fanica y sus grandes paredes de granito, cuya formaci\u00f3n es el resultado de las interacciones entre glaciares y rocas hace millones de a\u00f1os. El valle adem\u00e1s se caracteriza por albergar glaciares, bosques antiguos, r\u00edos pr\u00edstinos y especies en peligro de extinci\u00f3n como el alerce y el monito del monte.<\/p>\n\n\n\n<p>A pesar de su alto valor natural, cultural y tur\u00edstico, el valle de Cocham\u00f3 a\u00fan no est\u00e1 bajo protecci\u00f3n oficial y son los mismos operadores tur\u00edsticos y habitantes los que gestionan este ic\u00f3nico destino. \u201cLa carga tur\u00edstica de este lugar es alta y sin duda beneficia a muchas familias de la comuna, pero eso tambi\u00e9n es una amenaza. El Santuario de la Naturaleza Valle Cocham\u00f3 busca reconocer los valores ambientales y culturales y conciliar el cuidado de la naturaleza con los modos de vida de los habitantes del lugar. Esta figura es la \u00fanica protecci\u00f3n en donde puedes incorporar predios p\u00fablicos y privados, tambi\u00e9n es una figura legal que nos puede facilitar en el trabajo colaborativo que hemos hecho muchas veces sin el apoyo del estado\u201d, enfatiz\u00f3 Tatiana Sandoval, presidenta de la Organizaci\u00f3n Valle Cocham\u00f3.<\/p>\n\n\n\n<p>Durante este semestre las organizaciones han sostenido reuniones en distintas localidades de la comuna para socializar la petici\u00f3n de Santuario, adem\u00e1s de una reuni\u00f3n en el ministerio con la ministra de Bienes Nacionales Javiera Toro, la entrega de una carta de las organizaciones locales a Presidencia y la asistencia al Encuentro de \u00c1reas Protegidas y Comunidades Portal 2022, realizado en La Moneda el 17 de octubre, donde la ministra de Medio Ambiente comparti\u00f3 un panel con la Presidenta de la Organizaci\u00f3n Valle Cocham\u00f3, agrupaci\u00f3n que ingres\u00f3 la propuesta para la creaci\u00f3n del santuario a fines del 2021.<\/p>\n\n\n\n<p>En este encuentro la Ministra Maisa Roja mencion\u00f3 que la solicitud hab\u00eda sido recepcionada y que estaban a la espera de la respuesta de Bienes Nacionales. \u201cEl caso de Cocham\u00f3 es ejemplar y adem\u00e1s da la sensaci\u00f3n de que no fue una decisi\u00f3n dif\u00edcil porque es evidente el beneficio para la comunidad. La conservaci\u00f3n no se puede hacer sin la comunidad, es la comunidad que pide el beneficio y que va a cuidar de manera efectiva el lugar, que es una figura que tenemos en los Santuarios de la Naturaleza\u201d.<\/p>\n\n\n\n<p>La conservaci\u00f3n del patrimonio cultural es un punto importante dentro de los argumentos expuestos por la comunidad para la declaraci\u00f3n de un Santuario de la Naturaleza. La ruta hist\u00f3rica \u201cSendero La Junta\u201d, la cual conecta Chile con Argentina a trav\u00e9s del Paso El Le\u00f3n por el valle de Cocham\u00f3, fue la que dio origen al modo de vida de los Arrieros Cordilleranos de Paso el Le\u00f3n, considerados como un Tesoro Humano Vivo de Chile por el Ministerio de Cultura.<\/p>\n\n\n\n<p>\u201cLa gente local se ha hecho parte del cuidado del lugar porque les entrega sustento familiar y cuando le pones valor a algo cambia completamente, por ejemplo, en el caso del Santuario uno de los objetos de conservaci\u00f3n son los arrieros y el sendero hist\u00f3rico, esto le da valor a lo que antes no ten\u00eda. Hoy en d\u00eda las nuevas generaciones s\u00ed quieren cuidar el lugar\u201d enfatiz\u00f3 Tatiana.<\/p>\n\n\n\n<p>Actualmente las organizaciones se encuentran a la espera de la respuesta del Ministerio de Bienes Nacionales, que el 27 de octubre se pronunci\u00f3 mediante una carta enviada a la organizaci\u00f3n de Cocham\u00f3. \u201cA fines del 2021 ingresamos la petici\u00f3n formal junto a un informe t\u00e9cnico y en la \u00faltima visita del Presidente a la regi\u00f3n le entregamos una carta para pedirle que revise el caso del Santuario de Cocham\u00f3. Esa carta fue derivada al Ministerio de Medio Ambiente quienes solicitaron el pronunciamiento de Bienes Nacionales, que se encuentra revisando antecedentes t\u00e9cnicos a nivel regional\u201d concluy\u00f3 Tatiana.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/lh3.googleusercontent.com\/KHbMeAfE1_P31VKI_qcJud3nZ_4o2VAYECQGOEDqrmGD307q7DpuunkrdEbh3x8qMp9DCS2B_X9SRu_ZW7_TSuRpT2m85dDR3ZWScOGtIqfbBSRW8mCm4KfJKmzcwe_Oa1hTzo4aezlxWGLKynBiWsphgocsYn3Bg5IxO8eUa67mJSUYRyp2iEaElVtNGA\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Reuni\u00f3n Vidal Gormaz<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/lh6.googleusercontent.com\/HGDH3glRSucP4vrQTwFofiJl9pff2z2XBPuobRlnyCtxHwzy3EgLGqBHxTMMY4zENzcW_IGci9CGaGwoMmkGEZdpv7hMEt_IKHljbGzr5mVQauH45JaH_oh2dCNN4GCELELlgK5XpBJyZY0_ojmWJKllibJKN5wUS-39Zw8f3y5e-jsdyhF1oAOKsEVPQQ\" alt=\"\"\/><figcaption class=\"wp-element-caption\">La Junta, Cocham\u00f3<\/figcaption><\/figure>","protected":false},"featured_media":3718,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[],"class_list":["post-3717","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/3717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":4,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/3717\/revisions"}],"predecessor-version":[{"id":3722,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/3717\/revisions\/3722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/3718"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=3717"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=3717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}