{"id":4012,"date":"2023-04-21T14:58:26","date_gmt":"2023-04-21T14:58:26","guid":{"rendered":"https:\/\/zyn.xar.mybluehost.me\/website_cbdee90b\/?post_type=noticias&#038;p=4012"},"modified":"2023-04-21T16:24:58","modified_gmt":"2023-04-21T16:24:58","slug":"habitantes-de-cochamo-acuden-a-la-corte-suprema-por-problemas-de-conectividad-en-el-lago-tagua-tagua","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/habitantes-de-cochamo-acuden-a-la-corte-suprema-por-problemas-de-conectividad-en-el-lago-tagua-tagua\/","title":{"rendered":"Habitantes de Cocham\u00f3 acuden a la Corte Suprema por problemas de conectividad en el Lago Tagua Tagua"},"content":{"rendered":"<p><em>Habitantes de las zonas cordilleranas de Cocham\u00f3, en la Regi\u00f3n de Los Lagos, presentaron el viernes pasado un recurso de apelaci\u00f3n ante la Corte Suprema, luego de que se rechazara el recurso de protecci\u00f3n interpuesto en diciembre del a\u00f1o pasado ante la Corte de Apelaciones de Puerto Montt por deficiencias en la prestaci\u00f3n de servicios de conectividad lacustre en el Lago Tagua Tagua.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua.jpeg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-4013\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua.jpeg?w=827&amp;ssl=1 827w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua.jpeg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>La sentencia de la Corte de Apelaciones de Puerto Montt desestim\u00f3 el alegato de la comunidad cordillerana de Cocham\u00f3, cuyo argumento central plantea que&nbsp; la el servicio de transporte lacustre en el Lago Tagua Tagua, operado por Transportes Puelche S.A y subsidiado por el Estado para conectar zonas aisladas, se realizaba de manera discontinua, interrumpida, irregular e insuficiente, dificultando la conectividad de pasajeros y el traslado de carga que abastece esta aislada zona.Este recurso de protecci\u00f3n fue presentado en primera instancia en enero de este a\u00f1o, en medio de la temporada alta, donde el servicio de conectividad nuevamente no dio abasto, seg\u00fan lo mencionado en el recurso presentado y el relato de turistas, habitantes y autoridades comunales.<\/p>\n\n\n\n<p>Una de las medidas que tom\u00f3 el Gobierno dentro del programa Plan Verano 2023 del Ministerio de Transportes fue aumentar en un 30% los viajes de la nave Caupolic\u00e1n, anuncio que realiz\u00f3 el seremi de Transportes y Telecomunicaciones en la regi\u00f3n de Los Lagos, Pablo Joost, el d\u00eda 14 de enero, luego de que los vecinos ingresaron el recurso de reclamaci\u00f3n. La medida fue tomada por las autoridades principalmente para enfrentar el aumento de flujo de turistas en la temporada alta.&nbsp;<\/p>\n\n\n\n<p>A pesar de esta medida, los habitantes del sector cordillerano de Cocham\u00f3 mencionaron que las medidas implementadas por las autoridades fueron insuficientes. As\u00ed lo expres\u00f3 Sergio Cuevas, vocero del grupo de reclamantes \u201cLuego de que se ingres\u00f3 el recurso de protecci\u00f3n en la corte tuvimos un cambio en el recorrido subvencionado del Lago Tagua Tagua. Se sac\u00f3 la barcaza chica que hace dos recorridos y se subi\u00f3 a 14 recorridos de la barcaza Caupolic\u00e1n, que tiene m\u00e1s capacidad. Si bien es cierto mejor\u00f3, pero no fue suficiente porque a\u00fan quedan muchos veh\u00edculos por ambos lados, incluso llegando a estar 60 veh\u00edculos que no alcanzaban a cruzar y lo que se requiere son dos barcazas del mismo tama\u00f1o para poder asegurar la pasada de toda la gente, porque no es digno quedarse ni menos para los adultos mayores y ni\u00f1os\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s de las largas filas de espera, sobre todo durante la temporada de verano, la comunidad local afirma que hay constantes interrupciones de los zarpes durante todo el a\u00f1o por la falta de instrumentos de navegaci\u00f3n y medidas que hagan m\u00e1s eficiente la operaci\u00f3n de la barcaza. Tampoco se considera el aumento exponencial de la demanda en verano y la poca transparencia en los cobros, produciendo molestia en los usuarios. Por su parte, los turistas tambi\u00e9n han sido afectados por las largas esperas, incluso algunos han debido dormir en sus autos a la espera de cruzar, lo que afecta a la comunidad y deteriora la calidad del destino tur\u00edstico.<\/p>\n\n\n\n<p>Seg\u00fan Gabriela Barriga, abogada representante del grupo de vecinos que presentaron el recurso de protecci\u00f3n \u201cla frecuencia de los viajes no es suficiente para satisfacer la demanda de transporte de pasajeros y su carga, evidenci\u00e1ndose largas filas de autos esperando en ambos puertos siendo un problema de p\u00fablico conocimiento. Y esto ha sido as\u00ed, aun despu\u00e9s de que el Contrato de prestaci\u00f3n de servicios fuera modificado aumentando las frecuencias\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua-2.jpeg?resize=800%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-4014\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua-2.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua-2.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua-2.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua-2.jpeg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2023\/04\/barcaza-tagua-tagua-2.jpeg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>La sentencia de la Corte de Apelaciones de Puerto Montt argument\u00f3 que las entidades p\u00fablicas interpeladas han dado cumplimiento a la obligaci\u00f3n de ejecutar planes, iniciativas, proyectos y programas destinados a brindar soluci\u00f3n a los problemas de conectividad, cumpliendose con esto el principio de legalidad, debido a que las entidades p\u00fablicas realizaron la contrataci\u00f3n de un proveedor que otorga el servicio de transporte. Otra de las razones que manifest\u00f3 en defensa el Ministerio de Transporte, es que el cumplimiento eficaz del servicio se ve afectado debido a la ubicaci\u00f3n geogr\u00e1fica de esta zona y la escasa oferta de operadores disponibles, circunstancia que dificulta su inmediata soluci\u00f3n.<\/p>\n\n\n\n<p>\u201cLa sentencia no logra hacerse cargo de lo alegado por esta parte, pues no es suficiente que exista un proveedor que otorgue el servicio de transporte, sino que la prestaci\u00f3n del servicio lacustre debe prestarse de manera continua y regular de acuerdo a su Contrato y Bases\u201d explic\u00f3 la abogada representante de los habitantes de Cocham\u00f3. \u201cEs por ello que el 12 de abril presentamos un recurso de apelaci\u00f3n en contra de la sentencia, para que la Corte Suprema pueda revisar nuestras alegaciones\u201d.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan Barriga, \u201cen lo que va del 2023 siguen ocurriendo problemas de atochamientos en ambos puertos y siguen apareciendo relatos de personas que han quedado sin poder trasladarse a tiempo cu\u00e1ndo lo han requerido\u201d, por ejemplo, el 15 enero 2023 la turista Johana Bohmwld, public\u00f3 un reclamo en redes sociales, donde mencion\u00f3 que fueron por el d\u00eda a pasear a Llanada Grande y que se prioriza el cruce de veh\u00edculos con carros de arrastre y de carga, quedando los autos particulares \u201catrapados\u201d, sin ropa de abrigo adecuada y sin los medicamentos que necesitaban menores de edad.&nbsp;<\/p>\n\n\n\n<p>En el relato la usuaria coment\u00f3 que \u201cLogramos comunicarnos con ellos tomando se\u00f1al en un cerro porque en el mismo lugar no hay se\u00f1al y nos dijeron que vendr\u00edan por viaje especial solamente y aunque tuvi\u00e9ramos gente en urgencia si no pagamos los $275.000 no vendr\u00edan, adem\u00e1s deb\u00edamos tener el dinero en efectivo apenas ellos llegar\u00e1n porque de otra manera no sub\u00eda nadie\u201d. \u201cSolo pasaron 3 autos que pagaron $91.667 porque cobraron viaje especial y otros dos autos nos alojamos en el sector\u201d, relat\u00f3 la usuaria afectada.<\/p>\n\n\n\n<p>La abogada explic\u00f3 que las entidades p\u00fablicas \u201cdeben velar por la eficacia de la prestaci\u00f3n del servicio como parte del deber de coordinaci\u00f3n, sobre todo cuando hay una afectaci\u00f3n a los derechos fundamentales\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p>Mas informaci\u00f3n info@zyn.xar.mybluehost.me<\/p>","protected":false},"featured_media":4014,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[],"class_list":["post-4012","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/4012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":2,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/4012\/revisions"}],"predecessor-version":[{"id":4017,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/4012\/revisions\/4017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/4014"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=4012"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=4012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}