{"id":4656,"date":"2024-04-08T21:33:49","date_gmt":"2024-04-08T21:33:49","guid":{"rendered":"https:\/\/zyn.xar.mybluehost.me\/website_cbdee90b\/?post_type=noticias&#038;p=4656"},"modified":"2025-02-27T19:35:28","modified_gmt":"2025-02-27T19:35:28","slug":"puelo-patagonia-presenta-caso-de-conservacion-comunitaria-del-santuario-de-la-naturaleza-valle-cochamo-en-uc-de-villarrica","status":"publish","type":"noticias","link":"https:\/\/puelopatagonia.cl\/en\/noticias\/puelo-patagonia-presenta-caso-de-conservacion-comunitaria-del-santuario-de-la-naturaleza-valle-cochamo-en-uc-de-villarrica\/","title":{"rendered":"Puelo Patagonia presents case of community conservation of the Cocham\u00f3 Valley Nature Sanctuary at UC Villarrica"},"content":{"rendered":"<p>Tras casi un a\u00f1o de que m\u00e1s de 11 mil hect\u00e1reas en el Valle Cocham\u00f3 fuesen declaradas Santuario de la Naturaleza, el equipo de Puelo Patagonia estuvo en el Campus de Villarrica de la Pontificia Universidad Cat\u00f3lica de Chile (UC), en el curso de Ecolog\u00eda Humana y Territorio, exponiendo c\u00f3mo fue <strong>la experiencia para lograr esta figura de conservaci\u00f3n ambiental, que adem\u00e1s de resguardar los valores ambientales, busca ser un motor para el desarrollo econ\u00f3mico local.\u00a0<\/strong><\/p>\n\n\n\n<p>El foco de la charla fue que los estudiantes del Minor en Desarrollo Sustentable conocieran el proceso de preparaci\u00f3n y postulaci\u00f3n que llev\u00f3 m\u00e1s de dos a\u00f1os de trabajo colectivo entre la comunidad local, organizaciones de la sociedad civil e instituciones p\u00fablicas, y relevar la importancia que tiene esta vinculaci\u00f3n entre diversos actores territoriales para proyectar una iniciativa de esta \u00edndole.&nbsp;<\/p>\n\n\n\n<p>Gabriel G\u00f3mez, Encargado de Planificaci\u00f3n Territorial de Puelo Patagonia y quien expuso este tema en la universidad, valor\u00f3 la invitaci\u00f3n de la UC de Villarrica, ya que \u201ces importante que las nuevas generaciones en diversas regiones del pa\u00eds conozcan y se interesen por estas experiencias para que en el futuro puedan replicar en otros territorios modelos de conservaci\u00f3n participativas como este\u201d, cuenta.&nbsp;<\/p>\n\n\n\n<p>En esa misma l\u00ednea Jos\u00e9 Tom\u00e1s Ibarra, acad\u00e9mico de la UC y docente del Minor de Desarrollo Sustentable, destac\u00f3 la instancia ya que, para \u00e9l, el trabajo que ha hecho Puelo Patagonia junto a las organizaciones locales representa un modelo de colaboraci\u00f3n entre diversos actores para la protecci\u00f3n del medio ambiente, la promoci\u00f3n del desarrollo sostenible y la conservaci\u00f3n de la diversidad biocultural: \u201cSu experiencia entreg\u00f3 a los estudiantes una perspectiva pr\u00e1ctica y valiosa sobre c\u00f3mo, en sistemas socioecol\u00f3gicos complejos, se pueden abordar los desaf\u00edos de conservaci\u00f3n en contextos reales y de forma colectiva\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/04\/9-rio-cochamo-1-2048x1151-1.jpg?resize=800%2C450&#038;ssl=1\" alt=\"\" class=\"wp-image-4660\" srcset=\"https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/04\/9-rio-cochamo-1-2048x1151-1.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/04\/9-rio-cochamo-1-2048x1151-1.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/04\/9-rio-cochamo-1-2048x1151-1.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/04\/9-rio-cochamo-1-2048x1151-1.jpg?resize=1536%2C863&amp;ssl=1 1536w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/04\/9-rio-cochamo-1-2048x1151-1.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/puelopatagonia.cl\/wp-content\/uploads\/2024\/04\/9-rio-cochamo-1-2048x1151-1.jpg?w=1600&amp;ssl=1 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Cabe recordar que la solicitud y <strong>el trabajo para que el Valle Cocham\u00f3 fuese declarado Santuario de la Naturaleza fue impulsado por la Organizaci\u00f3n Valle de Cocham\u00f3<\/strong>, con el apoyo t\u00e9cnico de la ONG Puelo Patagonia, en un trabajo exhaustivo que logr\u00f3\u00a0 reunir a la comunidad local, incluyendo\u00a0 a organizaciones como la Agrupaci\u00f3n de Arrieros Valle Cocham\u00f3, la Comunidad Ind\u00edgena Antu Lemu N\u00b0 1219, la C\u00e1mara de Turismo Destino Cocham\u00f3, el Gremio de Turismo, la Junta de Vecinos N\u00b06 Cocham\u00f3, el Club de Adulto Mayor Cocham\u00f3 y la Municipalidad de Cocham\u00f3, entre otras.\u00a0<\/p>\n\n\n\n<p>Estas acciones, junto a una serie de reuniones con las autoridades pertinentes \u2013 entre ellas el compromiso del equipo regional de Bienes Nacionales \u2013, permitieron hacer realidad esta \u00e1rea protegida, en un proceso participativo que hoy permite asegurar una gesti\u00f3n y administraci\u00f3n sustentable en el tiempo, <strong>conservando 6.500 hect\u00e1reas de bosque maduro y 1.800 hect\u00e1reas de alerces milenarios, r\u00edos y humedales ribere\u00f1os que aportan nutrientes y vida al estuario de Reloncav\u00ed y un patrimonio geol\u00f3gico muy representativo de la Patagonia<\/strong>.\u00a0<\/p>\n\n\n\n<p>\u00bfTe gustar\u00eda saber m\u00e1s del Santuario de la Naturaleza Valle de Cocham\u00f3? Revisa m\u00e1s informaci\u00f3n en el Instagram oficial\u00a0 @santuariovallecochamo.\u00a0<\/p>","protected":false},"featured_media":4659,"template":"","meta":{"nf_dc_page":"","_joinchat":[],"_links_to":"","_links_to_target":""},"categorias_noticias":[30],"class_list":["post-4656","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categorias_noticias-conservacion"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/4656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":3,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/4656\/revisions"}],"predecessor-version":[{"id":4662,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/noticias\/4656\/revisions\/4662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media\/4659"}],"wp:attachment":[{"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/media?parent=4656"}],"wp:term":[{"taxonomy":"categorias_noticias","embeddable":true,"href":"https:\/\/puelopatagonia.cl\/en\/wp-json\/wp\/v2\/categorias_noticias?post=4656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}